{"id":24319,"date":"2025-02-20T09:23:56","date_gmt":"2025-02-20T13:23:56","guid":{"rendered":"https:\/\/www.emilysentourage.org\/?p=24319"},"modified":"2025-02-20T09:27:01","modified_gmt":"2025-02-20T13:27:01","slug":"accelerating-gene-therapy-delivery-for-cystic-fibrosis-emilys-entourage-to-convene-experts-at-2025-symposium","status":"publish","type":"post","link":"https:\/\/www.emilysentourage.org\/pt_br\/accelerating-gene-therapy-delivery-for-cystic-fibrosis-emilys-entourage-to-convene-experts-at-2025-symposium\/","title":{"rendered":"Acelerando o fornecimento de terapia g\u00eanica para fibrose c\u00edstica: Emily's Entourage reunir\u00e1 especialistas no Simp\u00f3sio de 2025"},"content":{"rendered":"<p><strong>Filad\u00e9lfia, PA - 20 de fevereiro de 2025<\/strong>-A Emily's Entourage (EE), uma organiza\u00e7\u00e3o pioneira sem fins lucrativos que acelera a pesquisa para os 10% finais da comunidade de fibrose c\u00edstica (FC), est\u00e1 pronta para sediar seu Simp\u00f3sio Cient\u00edfico de 2025, intitulado <i>\"A entrega de genes: Avan\u00e7os e desafios atrav\u00e9s de uma lente de FC,\"<\/i> de 23 a 26 de fevereiro de 2025, no Quorum do University City Science Center, na Filad\u00e9lfia, Pensilv\u00e2nia.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright wp-image-24324\" src=\"https:\/\/www.emilysentourage.org\/wp-content\/uploads\/2025-Symposium-Graphic-1000x610.png\" alt=\"\" width=\"560\" height=\"372\" srcset=\"https:\/\/www.emilysentourage.org\/wp-content\/uploads\/2025-Symposium-Graphic-300x200.png 300w, https:\/\/www.emilysentourage.org\/wp-content\/uploads\/2025-Symposium-Graphic-768x511.png 768w, https:\/\/www.emilysentourage.org\/wp-content\/uploads\/2025-Symposium-Graphic-18x12.png 18w, https:\/\/www.emilysentourage.org\/wp-content\/uploads\/2025-Symposium-Graphic-600x399.png 600w, https:\/\/www.emilysentourage.org\/wp-content\/uploads\/2025-Symposium-Graphic.png 1024w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/>O simp\u00f3sio deste ano tem como objetivo ampliar os limites do progresso no desenvolvimento de terapias baseadas em nucleot\u00eddeos para a FC, concentrando-se em um dos desafios mais cr\u00edticos e complexos dos tratamentos baseados em genes: sua distribui\u00e7\u00e3o. Embora tenham sido feitos avan\u00e7os, os obst\u00e1culos relacionados ao fornecimento eficaz de material gen\u00e9tico continuam sendo um grande obst\u00e1culo. Embora as terapias baseadas em nucleot\u00eddeos sejam promissoras para toda a comunidade de FC, a necessidade \u00e9 particularmente urgente para aqueles que est\u00e3o no 10% final da popula\u00e7\u00e3o de FC e que n\u00e3o se beneficiam das terapias moduladoras de CFTR atualmente dispon\u00edveis. Para esse grupo, o tempo \u00e9 essencial, e n\u00e3o h\u00e1 espa\u00e7o para esperar que o progresso se desenvolva nos cronogramas tradicionais.<\/p>\n<p>\"Acreditamos no poder de reunir os pesquisadores e l\u00edderes de pensamento mais brilhantes do mundo em uma \u00fanica sala. Nosso objetivo \u00e9 incentivar o compartilhamento aberto, estimular a colabora\u00e7\u00e3o, pensar grande e criar caminhos novos e r\u00e1pidos\", disse Emily Kramer-Golinkoff, MBE, cofundadora da EE. \"Ao reunir as principais mentes de dentro e de fora da comunidade cient\u00edfica e do setor de FC, este simp\u00f3sio est\u00e1 preparado para acelerar o fornecimento dessas terapias inovadoras.\"<\/p>\n<p>Presidido por Kevin Foskett, PhD, Isaac Ott Professor of Physiology na Perelman School of Medicine da University of Pennsylvania; Joan Lau, PhD, MBA, CEO da Spirovant Sciences, Inc.; e Paul McCray, Jr, MD, professor de pediatria e medicina pulmonar na University of Iowa, o evento contar\u00e1 com mais de 40 pesquisadores, inovadores e l\u00edderes de pensamento de renome mundial do meio acad\u00eamico, biotecnol\u00f3gico e farmac\u00eautico - tanto no espa\u00e7o da FC quanto fora dele. Esses especialistas examinar\u00e3o os avan\u00e7os de ponta e mergulhar\u00e3o nos desafios exclusivos de fornecer, com seguran\u00e7a e efic\u00e1cia, terapias baseadas em nucleot\u00eddeos para indiv\u00edduos com FC, uma etapa essencial para liberar todo o potencial da terapia baseada em genes. De olho nas oportunidades de tradu\u00e7\u00e3o, este simp\u00f3sio aborda n\u00e3o apenas a ci\u00eancia, mas tamb\u00e9m o poder da colabora\u00e7\u00e3o para transformar o cen\u00e1rio do tratamento da FC.<\/p>\n<p>O Simp\u00f3sio 2025 baseia-se nos esfor\u00e7os cont\u00ednuos da EE para acelerar o desenvolvimento terap\u00eautico para o 10% final de pessoas com FC, que n\u00e3o se beneficiam dos moduladores CFTR atuais devido a suas muta\u00e7\u00f5es gen\u00e9ticas raras. Os destaques do trabalho da EE incluem:<\/p>\n<ul>\n<li aria-level=\"1\">Premia\u00e7\u00e3o <a href=\"https:\/\/www.emilysentourage.org\/pt_br\/awarded-grants\/\" target=\"_blank\" rel=\"noopener\">38 bolsas de pesquisa<\/a> para os principais pesquisadores do mundo, resultando em mais de $52,3 milh\u00f5es em financiamentos subsequentes.<\/li>\n<li aria-level=\"1\">Implanta\u00e7\u00e3o de um modelo de filantropia de risco para a cria\u00e7\u00e3o de empresas <a href=\"https:\/\/www.emilysentourage.org\/pt_br\/emilys-entourage-celebrates-landmark-achievement-first-patient-dosed-with-novel-gene-therapy-developed-through-ees-visionary-model\/\" target=\"_blank\" rel=\"noopener\">uma empresa de terapia gen\u00e9tica para FC que est\u00e1 realizando um estudo cl\u00ednico de Fase 1\/2<\/a>.<\/li>\n<li aria-level=\"1\">Desenvolvimento de 37 fagos que trataram mais de 34 indiv\u00edduos com infec\u00e7\u00f5es resistentes a antibi\u00f3ticos.<\/li>\n<li aria-level=\"1\">Lan\u00e7amento <a href=\"https:\/\/www.emilysentourage.org\/pt_br\/ctc\/\" target=\"_blank\" rel=\"noopener\">Conex\u00e3o de ensaios cl\u00ednicos CF (CTC)<\/a>um banco de dados global de pacientes e o Clinical Trial Matchmaking Program para acelerar o recrutamento para essa popula\u00e7\u00e3o ultra-rara.<\/li>\n<\/ul>\n<p>\"Estamos incrivelmente orgulhosos do impulso cont\u00ednuo na pesquisa de terapia gen\u00e9tica da FC, mas reconhecemos que, para realmente fazer a diferen\u00e7a e desenvolver tratamentos, precisamos enfrentar as quest\u00f5es dif\u00edceis e colaborar entre as disciplinas\", disse Chandra Ghose, diretor cient\u00edfico da EE. \"Ao reunir um grupo t\u00e3o diversificado de l\u00edderes de pensamento, nosso objetivo \u00e9 estimular novas ideias, ultrapassar limites e, por fim, acelerar o cronograma de desenvolvimento de terapias para aqueles que mais precisam delas.\"<\/p>\n<p>A EE agradece aos patrocinadores da equipe dos sonhos do simp\u00f3sio de 2025, <b>Viatris,<\/b> <b>Terap\u00eautica molecular 4D<\/b>, <b>Vertex Pharmaceuticals, Inc., <\/b>patrocinadores de n\u00edvel violeta, <b>ReCode Therapeutics e Boomer Esiason Foundation,<\/b> e outros, cujo apoio torna poss\u00edvel esse evento fundamental e o progresso que ele proporciona.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Sobre a comitiva de Emily<\/b><\/p>\n<p>A Emily's Entourage \u00e9 uma organiza\u00e7\u00e3o inovadora 501(c)3 que acelera a pesquisa de novos tratamentos e de uma cura para os indiv\u00edduos no \u00faltimo 10% da popula\u00e7\u00e3o com fibrose c\u00edstica (FC) que n\u00e3o se beneficia das terapias direcionadas a muta\u00e7\u00f5es atualmente dispon\u00edveis. Desde 2011, a Emily's Entourage concedeu milh\u00f5es de d\u00f3lares em bolsas de pesquisa, lan\u00e7ou uma empresa de terapia gen\u00e9tica para FC em fase cl\u00ednica, desenvolveu um banco de dados de pacientes e um programa de combina\u00e7\u00e3o de ensaios cl\u00ednicos para acelerar o recrutamento de ensaios cl\u00ednicos e liderou esfor\u00e7os mundiais para impulsionar a pesquisa de alto impacto e o desenvolvimento de medicamentos. A organiza\u00e7\u00e3o foi destaque na m\u00eddia nacional, incluindo o New York Times, STAT, CNN, People e muito mais. Saiba mais em<a href=\"https:\/\/www.emilysentourage.org\/pt_br\/\"> emilysentourage.org<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Contato com a m\u00eddia<\/b><\/p>\n<p>Hannah Kleckner<\/p>\n<p>Diretor de Marketing e Comunica\u00e7\u00f5es<\/p>\n<p><a href=\"mailto:hannah@emilysentourage.org\">hannah@emilysentourage.org<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Filad\u00e9lfia, PA - 20 de fevereiro de 2025 - A Emily's Entourage (EE), uma organiza\u00e7\u00e3o pioneira sem fins lucrativos que acelera a pesquisa para o 10% final da comunidade de fibrose c\u00edstica (FC), est\u00e1 pronta para realizar seu Simp\u00f3sio Cient\u00edfico de 2025 intitulado \u201cThe Delivery of Genes: Advancements and Challenges Through a CF Lens\u201d, de 23 a 26 de fevereiro de 2025, no Quorum do University City Science Center, em... <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/www.emilysentourage.org\/pt_br\/accelerating-gene-therapy-delivery-for-cystic-fibrosis-emilys-entourage-to-convene-experts-at-2025-symposium\/\" class=\"excerpt-read-more\">Leia mais<\/a><\/p>","protected":false},"author":1719,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[178],"tags":[203,204,188,111,183],"class_list":["post-24319","post","type-post","status-publish","format-standard","hentry","category-press-releases","tag-2025-scientific-symposium","tag-ee-research","tag-gene-therapy","tag-research","tag-symposium"],"acf":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.emilysentourage.org\/pt_br\/wp-json\/wp\/v2\/posts\/24319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emilysentourage.org\/pt_br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emilysentourage.org\/pt_br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emilysentourage.org\/pt_br\/wp-json\/wp\/v2\/users\/1719"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emilysentourage.org\/pt_br\/wp-json\/wp\/v2\/comments?post=24319"}],"version-history":[{"count":5,"href":"https:\/\/www.emilysentourage.org\/pt_br\/wp-json\/wp\/v2\/posts\/24319\/revisions"}],"predecessor-version":[{"id":24328,"href":"https:\/\/www.emilysentourage.org\/pt_br\/wp-json\/wp\/v2\/posts\/24319\/revisions\/24328"}],"wp:attachment":[{"href":"https:\/\/www.emilysentourage.org\/pt_br\/wp-json\/wp\/v2\/media?parent=24319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emilysentourage.org\/pt_br\/wp-json\/wp\/v2\/categories?post=24319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emilysentourage.org\/pt_br\/wp-json\/wp\/v2\/tags?post=24319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}